{"id":16700,"date":"2025-04-17T13:30:54","date_gmt":"2025-04-17T19:30:54","guid":{"rendered":"https:\/\/fge.oaxaca.gob.mx\/?post_type=noticias&amp;p=8779"},"modified":"2025-04-17T13:30:54","modified_gmt":"2025-04-17T19:30:54","slug":"boletin-1391-fiscalia-de-oaxaca-ejecuta-orden-de-aprehension-contra-una-persona-por-robo-con-violencia-a-tienda-oxxo-en-la-region-de-la-cuenca","status":"publish","type":"noticias","link":"https:\/\/portal.fgeo.gob.mx\/index.php\/archivos\/noticias\/boletin-1391-fiscalia-de-oaxaca-ejecuta-orden-de-aprehension-contra-una-persona-por-robo-con-violencia-a-tienda-oxxo-en-la-region-de-la-cuenca","title":{"rendered":"BOLET\u00cdN 1391.- Fiscal\u00eda de Oaxaca ejecuta orden de aprehensi\u00f3n contra una persona por robo con violencia a tienda Oxxo en la regi\u00f3n de la Cuenca"},"content":{"rendered":"<p><strong>Oaxaca de Ju\u00e1rez a \u00a017 de abril \u00a0de 2025. \u2013<\/strong>\u00a0 Como parte de las acciones permanentes en el combate a la delincuencia, la Fiscal\u00eda General del Estado de Oaxaca (FGEO) ejecut\u00f3 una orden de aprehensi\u00f3n en contra de la persona del sexo masculino identificada como B.C.C., por el delito de robo con violencia por equiparaci\u00f3n en perjuicio de la Cadena Comercial Oxxo S.A. de C.V., ubicada en la regi\u00f3n de la Cuenca del Papaloapan.<\/p>\n<p>De acuerdo con lo establecido en el expediente penal, los hechos sucedieron el 15 de enero de 2025, en una sucursal Oxxo denominada &#8220;Tamayo&#8221;, ubicada en la calle Pedro Castillo de la colonia Ex Normal de la Ciudad de San Juan Bautista Tuxtepec, sitio al que llegaron dos personas para despojar de forma violenta a los trabajadores de dinero en efectivo y productos de la tienda.<\/p>\n<p>Ante estos hechos, la Fiscal\u00eda de Oaxaca inici\u00f3 las investigaciones correspondientes a trav\u00e9s de la Vicefiscal\u00eda Regional de la Cuenca, que dieron como resultado la detenci\u00f3n de B.C.C., y posteriormente fue puesto a disposici\u00f3n de la autoridad ministerial correspondiente para determinar su situaci\u00f3n jur\u00eddica.<\/p>\n<p>La investigaci\u00f3n revela que, por estos hechos, una persona fue detenida por Polic\u00edas Municipales de la zona el mismo d\u00eda que ocurri\u00f3 el robo.<\/p>\n<p>La Fiscal\u00eda General del Estado de Oaxaca mantiene de manera permanente acciones de inteligencia que permiten detectar objetivos generadores de violencia, as\u00ed como realizar acciones que contribuyan a la paz en todas las regiones de la entidad.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-8780\" src=\"https:\/\/portal.fgeo.gob.mx\/wp-content\/uploads\/2025\/04\/BOLET%C3%8DN-1391.-Fiscal%C3%ADa-de-Oaxaca-ejecuta-orden-de-aprehensi%C3%B3n-contra-una-persona-por-robo-con-violencia-a-tienda-Oxxo-en-la-regi%C3%B3n-de-la-Cuenca-_page-0001-232x300.jpg\" alt=\"\" width=\"232\" height=\"300\" \/><\/p>\n","protected":false},"author":2,"featured_media":8773,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"categoria_noticias":[],"class_list":["post-16700","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"acf":[],"mb":[],"mfb_rest_fields":["title","gutenberg_elementor_mode"],"_links":{"self":[{"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/wp\/v2\/noticias\/16700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/wp\/v2\/comments?post=16700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/wp\/v2\/media?parent=16700"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/wp\/v2\/tags?post=16700"},{"taxonomy":"categoria_noticias","embeddable":true,"href":"https:\/\/portal.fgeo.gob.mx\/index.php\/wp-json\/wp\/v2\/categoria_noticias?post=16700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}